{"id":1025,"date":"2022-01-25T15:47:47","date_gmt":"2022-01-25T14:47:47","guid":{"rendered":"https:\/\/www.artfood.at\/?p=1025"},"modified":"2023-04-18T13:00:49","modified_gmt":"2023-04-18T11:00:49","slug":"warum-weinte-herr-rossini","status":"publish","type":"post","link":"https:\/\/www.artfood.at\/index.php\/2022\/01\/25\/warum-weinte-herr-rossini\/","title":{"rendered":"Warum weinte Herr Rossini?"},"content":{"rendered":"<p>Ich gebe es gleich zu: ich kenne mich mit Opernmusik wirklich beinahezu fast gar nicht aus. Aber diesmal muss der alte Rossini herhalten, genauer gesagt der italienische Komponist Gioachino Antonio Rossini, 1792 in Pesaro in Italien das Licht der Welt erblickt, verblichen 1868 in Paris.<\/p>\n<figure id=\"attachment_1026\" aria-describedby=\"caption-attachment-1026\" style=\"width: 380px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\" wp-image-1026\" src=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920-300x199.jpg\" alt=\"\" width=\"380\" height=\"252\" srcset=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920-300x199.jpg 300w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920-1024x681.jpg 1024w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920-768x510.jpg 768w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920-1536x1021.jpg 1536w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/barber-gf15bb6bcc_1920.jpg 1920w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><figcaption id=\"caption-attachment-1026\" class=\"wp-caption-text\">Rossini: Der Barbier von Sevilla<\/figcaption><\/figure>\n<p>Er z\u00e4hlt, so sagt man mir, zu den bedeutendsten Opernkomponisten, verfasste neben gro\u00dfen Opern auch Hymnen, Geistliche Musik, Kantaten und \u201eZiergesang\u201c (was immer das genau ist) \u2013 und er hatte das Gl\u00fcck, bereits zu Lebzeiten ein gefeierter Star zu sein: \u201eIn den Zehner-, Zwanzigerjahren des 19. Jahrhunderts befand sich halb Europa im Taumel vor den Kl\u00e4ngen des Italieners \u2013 in Paris nicht anders als in London oder Wien.\u201c<\/p>\n<p>Herr Rossini wurde zu Lebzeiten aber nicht nur als musikalisches Genie gefeiert, sondern er war auch als leidenschaftlicher Esser und Genie\u00dfer bekannt \u2013 sonst h\u00e4tte er schwerlich seinen Weg hierher zu <span style=\"color: #eb684b;\">ArtFood<\/span> gefunden. Er scheint auch depressiv und kr\u00e4nklich gewesen zu sein, aber das soll uns hier nicht weiter Sorge bereiten.<\/p>\n<p><strong>&nbsp;<\/strong><strong>Warum weinte Herr Rossini?<br \/>\n<\/strong>\u201eIch gebe zu, dreimal in meinem Leben geweint zu haben: als meine erste Oper durchfiel, als ich Paganini die Violine spielen h\u00f6rte und als bei einem Bootspicknick ein getr\u00fcffelter Truthahn \u00fcber Bord fiel.\u201c, so wird er zitiert. Was man hier ablesen kann, ist der Stellenwert, den Essen f\u00fcr ihn als Vollblutmusiker hatte. Seine zweite Frau schrieb in einem Brief an einen Freund: \u201eDer Maestro und ich, wir leben, um zu essen, und diese Aufgabe erf\u00fcllen wir gewissenhaft.\u201c<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-1027\" src=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Composer_Rossini_G_1865_by_Carjat-239x300.jpeg\" alt=\"\" width=\"239\" height=\"300\" srcset=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Composer_Rossini_G_1865_by_Carjat-239x300.jpeg 239w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Composer_Rossini_G_1865_by_Carjat-814x1024.jpeg 814w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Composer_Rossini_G_1865_by_Carjat-768x966.jpeg 768w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Composer_Rossini_G_1865_by_Carjat.jpeg 1018w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/p>\n<p>Das ging schlie\u00dflich so weit, dass er vor seinem 40. Geburtstag die Arbeit an und mit der Musik beinahe zur G\u00e4nze sein lie\u00df \u2013 Geld hatte er angeblich bereits genug verdient \u2013 und die zweite H\u00e4lfte seines Lebens in Paris verbrachte, wo er sich seiner Leidenschaft f\u00fcr das gute Essen widmete. Und so werden ihm zahlreiche Zitate zum Thema Essen zugeschrieben. Hier ein paar Beispiele, die zeigen, wie innig f\u00fcr ihn die Verbindung zwischen seinen liebsten Besch\u00e4ftigungen war, der Musik und dem Essen:<\/p>\n<p style=\"text-align: center;\">\u201cEssen und Lieben, Singen und Verdauen, das sind im wahrsten Sinne des Wortes die vier Akte der Opera buffa, die man gemeinhin das Leben nennt &#8211; und das vergeht wie der Schaum einer Champagnerflasche. Wer es dahinschwinden l\u00e4\u00dft, ohne es genossen zu haben, ist ein Erznarr.\u201c<\/p>\n<p style=\"text-align: center;\">\u201eWas die Liebe f\u00fcr die Seele ist, das ist der Appetit f\u00fcr den Leib. Der Magen ist der Kapellmeister, der das gro\u00dfe Orchester unserer Leidenschaften dirigiert. Essen, Lieben, Singen, Verdauen sind die vier Akte der komischen Oper, die Leben hei\u00dft.\u201c<\/p>\n<p style=\"text-align: center;\">\u201eFalsche Gew\u00fcrze tun ebenso weh wie falsche T\u00f6ne.\u201c<\/p>\n<p style=\"text-align: center;\">\u201eDie Tr\u00fcffel ist f\u00fcrwahr der Mozart der Pilze. Zumal den &#8222;Don Juan&#8220; kann ich nur mit der Tr\u00fcffel vergleichen; beide haben das eine gemeinsam: Je \u00f6fter man sie genie\u00dft, desto gr\u00f6\u00dfere Reize entdeckt man.\u201c<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-1030\" src=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Rossini_Tournedos-300x287.jpeg\" alt=\"\" width=\"300\" height=\"287\" srcset=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Rossini_Tournedos-300x287.jpeg 300w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Rossini_Tournedos-1024x980.jpeg 1024w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Rossini_Tournedos-768x735.jpeg 768w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Rossini_Tournedos.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Rossinis Leidenschaft dem Essen gegen\u00fcber wurde zur Inspiration f\u00fcr K\u00f6che. Wenn man \u201eTournedos Rossini\u201c bestellt, bekommt man Rindsfilet mit G\u00e4nsestopfleber und schwarzen Tr\u00fcffeln. Oder, in einer rustikalen Variante, Bratwurst mit G\u00e4nsestopfleber.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter  wp-image-1028\" src=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Pizza-300x230.jpeg\" alt=\"\" width=\"352\" height=\"270\" srcset=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Pizza-300x230.jpeg 300w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Pizza-768x589.jpeg 768w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/Pizza.jpeg 881w\" sizes=\"(max-width: 352px) 100vw, 352px\" \/><\/p>\n<p><strong>Was mit Mayo \u2026 und Erdbeeren!<br \/>\n<\/strong>Eine andere M\u00f6glichkeit ist die \u201ePizza Rossini\u201c, erfunden in seiner Heimatstadt Pesaro: eine Pizza Margherita, verfeinert mit hart gekochten Eiern und Mayonnaise verfeinert. Um den Rossini-Rezepten ja kein Ende zu setzen, wird in Pesaro unerm\u00fcdlich weitergearbeitet: es gibt Snacks wie \u201ePiadina Rossini\u201c oder speziell gef\u00fcllte Cannelloni, auch \u201eMaccheroni alla Rossini\u201c sind im Angebot und \u201eSweet Rossini\u201c wurde ebenfalls erfunden. Soweit ich es herausgefunden habe, handelt es sich dabei um eine Art Kuchen mit Mandarinen, Vanille, Kardamom, Kaffee und Mandeln. Und wenn man dann noch Prosecco mit Erdbeerp\u00fcree&nbsp;mischt: ecco, der Rossini-Cocktail.<img loading=\"lazy\" class=\"aligncenter size-medium wp-image-1029\" src=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/rossini_cocktail-220x300.jpeg\" alt=\"\" width=\"220\" height=\"300\" srcset=\"https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/rossini_cocktail-220x300.jpeg 220w, https:\/\/www.artfood.at\/wp-content\/uploads\/2022\/01\/rossini_cocktail.jpeg 513w\" sizes=\"(max-width: 220px) 100vw, 220px\" \/>Und in der Casa Rossini wird eine sogenannte \u201eDegustazione audioguidata Rossini Gourmet\u201c, also eine \u201edegustazione teatralizzata\u201d angeboten. W\u00e4hrend eines mehrg\u00e4ngigen Dinners, das den Feinschmecker Rossini feiert, tr\u00e4gt jeder Teilnehmer, jede Teilnehmerin bei Tisch Kopfh\u00f6rer \u2013 man genie\u00dft das Essen, h\u00f6rt Geschichten aus dem Leben des Komponisten, lauscht seiner Musik \u2013 und muss sich in all der Zeit mit keinem der anderen Anwesenden unterhalten. \ud83d\ude42<\/p>\n<hr>\n<p><strong>Infos &amp; Quellen<\/strong><br \/>\n*Kulinarische Infos zu Rossini, z.B.: <a href=\"https:\/\/www.rossinigesellschaft.de\/de\/kulinaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rossinigesellschaft<\/a>, <a href=\"https:\/\/www.pesaromusei.it\/rossini-gourmet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Museum Pesaro<\/a>, &nbsp;<a href=\"http:\/\/www.gioachinorossini.it\/it\/special\/gourmet\" target=\"_blank\" rel=\"noopener noreferrer\">Rossini Gourmet<\/a>, <a href=\"https:\/\/www.italiangourmet.it\/sweet-rossini\" target=\"_blank\" rel=\"noopener noreferrer\">Italian Gourmet<\/a>.<\/p>\n<p>Bilder:<br \/>\n*Barbier von Sevilla: <a href=\"https:\/\/pixabay.com\/de\/photos\/barbier-sevilla-oper-leistung-895148\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pixabay<\/a>.<br \/>\n*Rossini Fotografie von \u00c9tienne Carjat: <a href=\"https:\/\/de.wikipedia.org\/wiki\/Gioachino_Rossini#\/media\/Datei:Composer_Rossini_G_1865_by_Carjat.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">Wikipedia<\/a>.<br \/>\n*Tournedos Rossini: <a href=\"https:\/\/commons.wikimedia.org\/wiki\/Category:Tournedos_Rossini?uselang=de#\/media\/File:Pcs34560_IMG1907.JPG\" target=\"_blank\" rel=\"noopener noreferrer\">Wikimedia<\/a>.<br \/>\n*Pizza Rossini: <a href=\"https:\/\/www.silviocicchi.com\/pizzachef\/pizza-rossini-una-sinfonia-di-sapori\/?lang=en\" target=\"_blank\" rel=\"noopener noreferrer\">Silvio Cicchi<\/a>.<br \/>\n*Rossini cocktail: <a href=\"https:\/\/www.prosecco.wine\/de\/cocktails\/rossini\" target=\"_blank\" rel=\"noopener noreferrer\">Prosecco.wine<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich gebe es gleich zu: ich kenne mich mit Opernmusik wirklich beinahezu fast gar nicht aus. Aber diesmal muss der alte Rossini herhalten, genauer gesagt der italienische Komponist Gioachino Antonio&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,32,15],"tags":[],"_links":{"self":[{"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/posts\/1025"}],"collection":[{"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":6,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/posts\/1025\/revisions"}],"predecessor-version":[{"id":1222,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/posts\/1025\/revisions\/1222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/media\/1028"}],"wp:attachment":[{"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/media?parent=1025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/categories?post=1025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.artfood.at\/index.php\/wp-json\/wp\/v2\/tags?post=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}